{"id":5067,"date":"2024-07-02T16:58:46","date_gmt":"2024-07-02T15:58:46","guid":{"rendered":"https:\/\/goldenrod-lark-979099.hostingersite.com\/?page_id=5067"},"modified":"2024-07-02T17:25:02","modified_gmt":"2024-07-02T16:25:02","slug":"access-control","status":"publish","type":"page","link":"https:\/\/click-me.lt\/lt\/access-control\/","title":{"rendered":"Access Control"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row row top-row wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"vc_column_container col-md-12\"><div class=\"wpb_wrapper vc_column-inner\"><h2  class=\"vc_custom_heading vc_do_custom_heading wpb_custom_aa365bd5046e8294520b4e73732b9d15 align-left\" ><strong>Access Control<\/strong><\/h2><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"vc_column_container col-md-12 col-lg-10 col-12\"><div class=\"wpb_wrapper vc_column-inner\">\r\n\t<div class=\"wpb_text_column wpb_content_element featured lead wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>Access control is a security technique used to regulate who or what can view or use resources in a computing environment. It ensures that only authorized individuals have access to specific areas, information, or resources, protecting sensitive data and physical locations from unauthorized access. Access control systems are critical in both physical security (controlling entry to buildings or rooms) and information security (managing access to data and systems).<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><div class=\"push-top vc_column_container col-md-12 col-lg-2 col-12\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"vc_btn3-container vc_btn3-inline vc_do_btn\" >\r\n\t<a class=\"vc_btn3 vc_btn3-shape-default wpb_custom_6687b26f39488ddbb85ddb3c1ce8e111 btn btn-lg btn-primary\" href=\"#form-seperator\" title=\"\">Susisiekite!<\/a>\t<\/div>\r\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"vc_column_container col-md-12\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-separator tall\"><hr class=\"separator-line  wpb_content_element align_center\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"vc_column_container col-md-3\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-content-box featured-boxes wpb_content_element\"><div class=\"featured-box featured-box-primary featured-box-effect-1\"><div class=\"box-content\" style=\"\"><i class=\"icon-featured fas fa-eye\"><\/i>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<h4 class=\"text-uppercase\">User Authentication<\/h4>\n<p>Confirms the identity of users through various methods such as passwords, PINs, biometric scans, or smart cards, ensuring only authorized personnel can access the system.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_column_container col-md-3\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-content-box featured-boxes wpb_content_element\"><div class=\"featured-box featured-box-secondary featured-box-effect-1\"><div class=\"box-content\" style=\"\"><i class=\"icon-featured fas fa-running\"><\/i>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<h4 class=\"text-uppercase\">Real-Time Monitoring and Alerts<\/h4>\n<p>Provides immediate notifications and the ability to monitor access events in real time, allowing for quick responses to suspicious activities or security breaches.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_column_container col-md-3\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-content-box featured-boxes wpb_content_element\"><div class=\"featured-box featured-box-tertiary featured-box-effect-1\"><div class=\"box-content\" style=\"\"><i class=\"icon-featured fas fa-laptop\"><\/i>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<h4 class=\"text-uppercase\">Scalability<\/h4>\n<p>Easily scales to accommodate a growing number of users and locations, ensuring that the system can expand with the organization\u2019s needs without significant changes or disruptions.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_column_container col-md-3\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-content-box featured-boxes wpb_content_element\"><div class=\"featured-box featured-box-quaternary featured-box-effect-1\"><div class=\"box-content\" style=\"\"><i class=\"icon-featured fa fa-cogs\"><\/i>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<h4 class=\"text-uppercase\">Remote Access Management<\/h4>\n<p>Allows administrators to manage and configure access control settings from anywhere, providing flexibility and convenience, especially for large or multi-site organizations.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"vc_column_container col-md-12\" id=\"form-seperator\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-separator tall\"><hr class=\"separator-line  wpb_content_element align_center\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"vc_column_container col-md-12\"><div class=\"wpb_wrapper vc_column-inner\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5057-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"5057\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/lt\/wp-json\/wp\/v2\/pages\/5067#wpcf7-f5057-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/lt\/wp-json\/wp\/v2\/pages\/5067#wpcf7-f5057-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5057\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5057-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<h2 class=\"short\"><strong>Susisiekite<\/strong> Us<\/h2>\n<div class=\"row\">\n    <div class=\"col-lg-6\">\n        <div class=\"form-group\">\n            <label for=\"contact-name\">Vardas *<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" id=\"contact-name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-6\">\n        <div class=\"form-group\">\n            <label for=\"contact-email\">J\u016bs\u0173 elektroninio pa\u0161to adresas *<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" id=\"contact-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-12\">\n        <div class=\"form-group\">\n            <label for=\"selected-inquiries\">Paklausimai<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-167\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required selected-inquiries\" id=\"selected-inquiries\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-167\"><option value=\"Access Control\">Access Control<\/option><\/select><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-12\">\n        <div class=\"form-group\">\n            <label for=\"contact-subject\">Tema<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text form-control\" id=\"contact-subject\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-12\">\n        <div class=\"form-group\">\n            <label for=\"contact-message\">J\u016bs\u0173 \u017einut\u0117<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" id=\"contact-message\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n        <\/div>\n    <\/div>\n\n    <div class=\"col-lg-12\">\n        <label for=\"contact-captcha\">\u017dmogaus patvirtinimas*<\/label>\n    <\/div>\n    <div class=\"col-lg-3\">\n        <div class=\"form-group\">\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"your-captcha\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-captchar form-control\" id=\"contact-captcha\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-captcha\" \/><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-3\">\n        <div class=\"form-group\">\n            <input type=\"hidden\" name=\"_wpcf7_captcha_challenge_your-captcha\" value=\"1597962334\" \/><img decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-your-captcha\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/click-me.lt\/wp-content\/uploads\/wpcf7_captcha\/1597962334.png\" \/>\n        <\/div>\n    <\/div>\n\n    <div class=\"col-lg-12\">\n        <div class=\"form-group\">\n            <input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary btn-lg\" type=\"submit\" value=\"Si\u0173sti \u017einut\u0119\" \/>\n        <\/div>\n    <\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"62\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"lt\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Access Control Access control is a security technique used to regulate who or what can view or use resources in a computing environment. It ensures that only authorized individuals have access to specific areas, information, or resources, protecting sensitive data and physical locations from unauthorized access. Access control systems are critical in both physical security [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5067","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/pages\/5067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/comments?post=5067"}],"version-history":[{"count":3,"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/pages\/5067\/revisions"}],"predecessor-version":[{"id":5085,"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/pages\/5067\/revisions\/5085"}],"wp:attachment":[{"href":"https:\/\/click-me.lt\/lt\/wp-json\/wp\/v2\/media?parent=5067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}